{"id":76,"date":"2019-12-07T18:28:38","date_gmt":"2019-12-07T18:28:38","guid":{"rendered":"https:\/\/santiagotrigueros.com\/?page_id=76"},"modified":"2021-03-20T22:05:40","modified_gmt":"2021-03-20T22:05:40","slug":"contacto","status":"publish","type":"page","link":"https:\/\/santiagotrigueros.com\/index.php\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-block\" id=\"wpforms-605\"><form id=\"wpforms-form-605\" class=\"wpforms-validate wpforms-form\" data-formid=\"605\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/76\" data-token=\"b85abcb5c39b9f17b45ae8d6c9fe3174\" data-token-time=\"1788331061\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-605-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-605-field_0\">Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-605-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" required><\/div><div id=\"wpforms-605-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-605-field_1\">Correo electr\u00f3nico <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-605-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-605-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-605-field_2\">Comentario o mensaje <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-605-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"605\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/pages\/76\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-605\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-76","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacto - Santiago Trigueros Composer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/santiagotrigueros.com\/index.php\/contacto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacto - Santiago Trigueros Composer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/santiagotrigueros.com\/index.php\/contacto\/\" \/>\n<meta property=\"og:site_name\" content=\"Santiago Trigueros Composer\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-20T22:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/santiagotrigueros.com\/wp-content\/uploads\/2020\/08\/cropped-cropped-nota-de-prensa-hmma-2020-3.jpg?fit=1920%2C1079&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/santiagotrigueros.com\\\/index.php\\\/contacto\\\/\",\"url\":\"https:\\\/\\\/santiagotrigueros.com\\\/index.php\\\/contacto\\\/\",\"name\":\"Contacto - Santiago Trigueros Composer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/santiagotrigueros.com\\\/#website\"},\"datePublished\":\"2019-12-07T18:28:38+00:00\",\"dateModified\":\"2021-03-20T22:05:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/santiagotrigueros.com\\\/index.php\\\/contacto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/santiagotrigueros.com\\\/index.php\\\/contacto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/santiagotrigueros.com\\\/index.php\\\/contacto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/santiagotrigueros.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/santiagotrigueros.com\\\/#website\",\"url\":\"https:\\\/\\\/santiagotrigueros.com\\\/\",\"name\":\"Santiago Trigueros Composer\",\"description\":\"SANTIAGOTRIGUEROS.COM\",\"publisher\":{\"@id\":\"https:\\\/\\\/santiagotrigueros.com\\\/#\\\/schema\\\/person\\\/bd1efe6fcc415973693b0420e99218be\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/santiagotrigueros.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/santiagotrigueros.com\\\/#\\\/schema\\\/person\\\/bd1efe6fcc415973693b0420e99218be\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacto - Santiago Trigueros Composer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/santiagotrigueros.com\/index.php\/contacto\/","og_locale":"es_ES","og_type":"article","og_title":"Contacto - Santiago Trigueros Composer","og_url":"https:\/\/santiagotrigueros.com\/index.php\/contacto\/","og_site_name":"Santiago Trigueros Composer","article_modified_time":"2021-03-20T22:05:40+00:00","og_image":[{"width":1920,"height":1079,"url":"https:\/\/i0.wp.com\/santiagotrigueros.com\/wp-content\/uploads\/2020\/08\/cropped-cropped-nota-de-prensa-hmma-2020-3.jpg?fit=1920%2C1079&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/santiagotrigueros.com\/index.php\/contacto\/","url":"https:\/\/santiagotrigueros.com\/index.php\/contacto\/","name":"Contacto - Santiago Trigueros Composer","isPartOf":{"@id":"https:\/\/santiagotrigueros.com\/#website"},"datePublished":"2019-12-07T18:28:38+00:00","dateModified":"2021-03-20T22:05:40+00:00","breadcrumb":{"@id":"https:\/\/santiagotrigueros.com\/index.php\/contacto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/santiagotrigueros.com\/index.php\/contacto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/santiagotrigueros.com\/index.php\/contacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/santiagotrigueros.com\/"},{"@type":"ListItem","position":2,"name":"Contacto"}]},{"@type":"WebSite","@id":"https:\/\/santiagotrigueros.com\/#website","url":"https:\/\/santiagotrigueros.com\/","name":"Santiago Trigueros Composer","description":"SANTIAGOTRIGUEROS.COM","publisher":{"@id":"https:\/\/santiagotrigueros.com\/#\/schema\/person\/bd1efe6fcc415973693b0420e99218be"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/santiagotrigueros.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/santiagotrigueros.com\/#\/schema\/person\/bd1efe6fcc415973693b0420e99218be","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g","caption":"admin"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/87966ebf0130a0cb7460bc8e4e2436bd11d03baef3ffee6f647697a36fbeafe5?s=96&d=mm&r=g"}}]}},"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":0,"href":"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"wp:attachment":[{"href":"https:\/\/santiagotrigueros.com\/index.php\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}